{"id":687,"date":"2023-12-21T09:49:19","date_gmt":"2023-12-21T08:49:19","guid":{"rendered":"https:\/\/www.alphatax.de\/?page_id=687"},"modified":"2025-01-13T16:11:49","modified_gmt":"2025-01-13T15:11:49","slug":"start","status":"publish","type":"page","link":"https:\/\/www.alphatax.de\/fr\/","title":{"rendered":"Start"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-687","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Start - AlphaTax DE<\/title>\n<meta name=\"description\" content=\"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alphatax.ch\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Start - AlphaTax DE\" \/>\n<meta property=\"og:description\" content=\"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alphatax.ch\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"AlphaTax DE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T15:11:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/\",\"url\":\"https:\\\/\\\/www.alphatax.ch\\\/fr\\\/\",\"name\":\"Start - AlphaTax DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/#website\"},\"datePublished\":\"2023-12-21T08:49:19+00:00\",\"dateModified\":\"2025-01-13T15:11:49+00:00\",\"description\":\"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alphatax.ch\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alphatax.ch\\\/fr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alphatax.ch\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Start\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/\",\"name\":\"AlphaTax DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alphatax.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Start - AlphaTax DE","description":"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alphatax.ch\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Start - AlphaTax DE","og_description":"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.","og_url":"https:\/\/www.alphatax.ch\/fr\/","og_site_name":"AlphaTax DE","article_modified_time":"2025-01-13T15:11:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alphatax.de\/fr\/","url":"https:\/\/www.alphatax.ch\/fr\/","name":"Start - AlphaTax DE","isPartOf":{"@id":"https:\/\/www.alphatax.de\/fr\/#website"},"datePublished":"2023-12-21T08:49:19+00:00","dateModified":"2025-01-13T15:11:49+00:00","description":"AlphaTax propose des rapports fiscaux efficaces et fiables pour les banques, des donn\u00e9es brutes au rapport final.","breadcrumb":{"@id":"https:\/\/www.alphatax.ch\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alphatax.ch\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alphatax.ch\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.alphatax.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Start"}]},{"@type":"WebSite","@id":"https:\/\/www.alphatax.de\/fr\/#website","url":"https:\/\/www.alphatax.de\/fr\/","name":"AlphaTax DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alphatax.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/pages\/687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/comments?post=687"}],"version-history":[{"count":1,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/pages\/687\/revisions"}],"predecessor-version":[{"id":688,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/pages\/687\/revisions\/688"}],"wp:attachment":[{"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/media?parent=687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/categories?post=687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alphatax.de\/fr\/wp-json\/wp\/v2\/tags?post=687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}